{"id":1547,"date":"2025-04-28T09:31:15","date_gmt":"2025-04-28T09:31:15","guid":{"rendered":"https:\/\/akkuokok.de\/blog\/?p=1547"},"modified":"2025-04-28T09:31:16","modified_gmt":"2025-04-28T09:31:16","slug":"das-asus-zenbook-s-13-oled-ist-ein-hervorragender-laptop","status":"publish","type":"post","link":"https:\/\/www.akkuokok.de\/blog\/2025\/04\/28\/das-asus-zenbook-s-13-oled-ist-ein-hervorragender-laptop\/","title":{"rendered":"Das Asus Zenbook S 13 OLED ist ein hervorragender Laptop"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Mit seinem leichten Geh\u00e4use, dem wundersch\u00f6nen OLED-Display und der langen Akkulaufzeit wird das Zenbook S 13 OLED PC-Benutzer mit Sicherheit begeistern. Aus diesem Grund erh\u00e4lt das Asus Zenbook S 13 OLED nicht die Aufmerksamkeit, die es verdient. Dieser 13-Zoll-Laptop ist in vielerlei Hinsicht dem XPS, MacBook und Yoga ebenb\u00fcrtig, hat jedoch keinen bekannteren Namen. Es ist d\u00fcnner und leichter als die Konkurrenz, verf\u00fcgt \u00fcber einen leistungsstarken AMD-Prozessor und trotz seines beeindruckenden 2,8K-OLED-Displays<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u><a target=\"_blank\" href=\"https:\/\/www.akkuokok.de\/brand-Asus-2-laptop_battery\" rel=\"noreferrer noopener\">Zenbook S 13 OLED Laptop-Akku<\/a><\/u><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit einer einzigen Ladung k\u00f6nnen Sie das Ger\u00e4t einen ganzen Tag lang nutzen. Asus Zenbook S 13 OLED<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Asus Zenbook S 13 OLED ist ein extrem portabler Laptop mit ultraleichtem Geh\u00e4use, einem wundersch\u00f6nen 2,8K-Display und einer \u00fcberraschend langen<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Zenbook S 13 OLED Laptop-Akku<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Leben. Vorteile<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Schlankes, ultraleichtes Design; Gute Leistung (aber nicht die schnellste);<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u><a href=\"https:\/\/www.akkuokok.de\/brand-Asus-2-laptop_battery\" target=\"_blank\" rel=\"noreferrer noopener\">Zenbook S 13 OLED Laptop-Akku<\/a><\/u><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Langes Leben; wundersch\u00f6nes 2,8K-OLED-Display; sch\u00f6ne Farbauswahl. Diese Verhaltens\u00e4nderung ist gr\u00f6\u00dftenteils auf die geringe Gr\u00f6\u00dfe (11,7 x 8,3 x 0,6 Zoll) und das Gewicht von 2,2 Pfund des Zenbook S13 OLED zur\u00fcckzuf\u00fchren \u2013 das Bewegen dieses Laptops von Raum zu Raum ist m\u00fchelos und Windows startet sofort, wenn das System aktiviert wird. Das Zenbook S 13 l\u00f6st den Widerspruch zwischen Mobilit\u00e4t und Langlebigkeit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die meisten anderen bieten nur Mobilit\u00e4t und Haltbarkeit. Der Fingerabdrucksensor ist schnell und zuverl\u00e4ssig, aber nicht so praktisch wie die Gesichtserkennungsfunktionen der meisten anderen High-End-Laptops. Die vielleicht gr\u00f6\u00dfte St\u00e4rke des Zenbook S 13 ist seine au\u00dfergew\u00f6hnliche Akkulaufzeit. Bislang musste man bei der Entscheidung f\u00fcr ein OLED-Display Kompromisse bei der Akkulaufzeit eingehen. In unserem Akkutest war die Videowiedergabe bei 200 Nits Bildschirmhelligkeit<strong><a href=\"https:\/\/www.akkuokok.de\/brand-Asus-2-laptop_battery\" target=\"_blank\" rel=\"noreferrer noopener\">Zenbook S 13 OLED Laptop-Akku<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Akkulaufzeit mit OLED-Display und Ryzen 6000 CPU betrug 11 Stunden und 10 Minuten. Dennoch hielt der S 13 OLED einen ganzen Tag lang durch, oder in meinem Fall einen transkontinentalen Flug.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asus ben\u00f6tigt nur wenige Zutaten, um das Gericht noch k\u00f6stlicher zu machen. Ein einfaches Upgrade auf eine 1080p-Infrarotkamera w\u00fcrde den gr\u00f6\u00dften Fehler des Zenbooks beheben. Wenn das meine gr\u00f6\u00dfte Sorge ist, dann wissen Sie, dass das Zenbook S 13 OLED ein Spitzenprodukt ist \u2013 w\u00fcrdig, neben Ger\u00e4ten wie dem XPS 13 und dem MacBook Air zu stehen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entdecke Produkte der Marke Asus im Bereich Laptop Akku.Kaufen Sie g\u00fcnstige&nbsp;<strong><u><a href=\"https:\/\/www.akkuokok.de\/brand-Asus-2-laptop_battery\" target=\"_blank\" rel=\"noreferrer noopener\">Asus Laptop Akku<\/a><\/u><\/strong>&nbsp;in der Deutschland! 12 Monate Garantie, 30 Tage Geld zur\u00fcck.<br>\uff1e\uff1e\uff1e\uff1e\uff1e\uff1e\uff1e\uff1e\uff1e\uff1e\uff1e\uff1e\uff1e\uff1e\uff1e\uff1e\uff1e\uff1e\uff1e\uff1e<strong><u><a href=\"https:\/\/www.akkuokok.de\/detail-asus-C22N2206-battery-model-25BA83U4C\" target=\"_blank\" rel=\"noreferrer noopener\">Akku C22N2206 f\u00fcr Asus ZenBook S 13 UX5304MA UX5304VA 8140mAh, 7.74V<\/a><\/u><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit seinem leichten Geh\u00e4use, dem wundersch\u00f6nen OLED-Display und der langen Akkulaufzeit wird das Zenbook S 13 OLED PC-Benutzer mit Sicherheit begeistern. Aus diesem Grund erh\u00e4lt das Asus Zenbook S 13 OLED nicht die Aufmerksamkeit, die es verdient. Dieser 13-Zoll-Laptop ist in vielerlei Hinsicht dem XPS, MacBook und Yoga ebenb\u00fcrtig, hat jedoch keinen bekannteren Namen. Es [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1547","post","type-post","status-publish","format-standard","hentry","category-laptop-akku"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Das Asus Zenbook S 13 OLED ist ein hervorragender Laptop - Akkus &amp; Ladeger\u00e4te Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.akkuokok.de\/blog\/2025\/04\/28\/das-asus-zenbook-s-13-oled-ist-ein-hervorragender-laptop\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Das Asus Zenbook S 13 OLED ist ein hervorragender Laptop - Akkus &amp; Ladeger\u00e4te Blog\" \/>\n<meta property=\"og:description\" content=\"Mit seinem leichten Geh\u00e4use, dem wundersch\u00f6nen OLED-Display und der langen Akkulaufzeit wird das Zenbook S 13 OLED PC-Benutzer mit Sicherheit begeistern. Aus diesem Grund erh\u00e4lt das Asus Zenbook S 13 OLED nicht die Aufmerksamkeit, die es verdient. Dieser 13-Zoll-Laptop ist in vielerlei Hinsicht dem XPS, MacBook und Yoga ebenb\u00fcrtig, hat jedoch keinen bekannteren Namen. Es [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.akkuokok.de\/blog\/2025\/04\/28\/das-asus-zenbook-s-13-oled-ist-ein-hervorragender-laptop\/\" \/>\n<meta property=\"og:site_name\" content=\"Akkus &amp; Ladeger\u00e4te Blog\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-28T09:31:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-28T09:31:16+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.akkuokok.de\\\/blog\\\/2025\\\/04\\\/28\\\/das-asus-zenbook-s-13-oled-ist-ein-hervorragender-laptop\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.akkuokok.de\\\/blog\\\/2025\\\/04\\\/28\\\/das-asus-zenbook-s-13-oled-ist-ein-hervorragender-laptop\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.akkuokok.de\\\/blog\\\/#\\\/schema\\\/person\\\/0e78375375f076b526d126d5e46432b5\"},\"headline\":\"Das Asus Zenbook S 13 OLED ist ein hervorragender Laptop\",\"datePublished\":\"2025-04-28T09:31:15+00:00\",\"dateModified\":\"2025-04-28T09:31:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.akkuokok.de\\\/blog\\\/2025\\\/04\\\/28\\\/das-asus-zenbook-s-13-oled-ist-ein-hervorragender-laptop\\\/\"},\"wordCount\":415,\"commentCount\":0,\"articleSection\":[\"Laptop Akku\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.akkuokok.de\\\/blog\\\/2025\\\/04\\\/28\\\/das-asus-zenbook-s-13-oled-ist-ein-hervorragender-laptop\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.akkuokok.de\\\/blog\\\/2025\\\/04\\\/28\\\/das-asus-zenbook-s-13-oled-ist-ein-hervorragender-laptop\\\/\",\"url\":\"https:\\\/\\\/www.akkuokok.de\\\/blog\\\/2025\\\/04\\\/28\\\/das-asus-zenbook-s-13-oled-ist-ein-hervorragender-laptop\\\/\",\"name\":\"Das Asus Zenbook S 13 OLED ist ein hervorragender Laptop - Akkus &amp; Ladeger\u00e4te Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.akkuokok.de\\\/blog\\\/#website\"},\"datePublished\":\"2025-04-28T09:31:15+00:00\",\"dateModified\":\"2025-04-28T09:31:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.akkuokok.de\\\/blog\\\/#\\\/schema\\\/person\\\/0e78375375f076b526d126d5e46432b5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.akkuokok.de\\\/blog\\\/2025\\\/04\\\/28\\\/das-asus-zenbook-s-13-oled-ist-ein-hervorragender-laptop\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.akkuokok.de\\\/blog\\\/2025\\\/04\\\/28\\\/das-asus-zenbook-s-13-oled-ist-ein-hervorragender-laptop\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.akkuokok.de\\\/blog\\\/2025\\\/04\\\/28\\\/das-asus-zenbook-s-13-oled-ist-ein-hervorragender-laptop\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.akkuokok.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Das Asus Zenbook S 13 OLED ist ein hervorragender Laptop\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.akkuokok.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.akkuokok.de\\\/blog\\\/\",\"name\":\"Akkus &amp; Ladeger\u00e4te Blog\",\"description\":\"Akkus &amp; Ladeger\u00e4te f\u00fcr Smartphone, Tablet, Werkzeug &amp; Notebook!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.akkuokok.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.akkuokok.de\\\/blog\\\/#\\\/schema\\\/person\\\/0e78375375f076b526d126d5e46432b5\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c0644ade7f549321e61eca3fe284692ad929ecca361fd150d7cd3f07cc5b1e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c0644ade7f549321e61eca3fe284692ad929ecca361fd150d7cd3f07cc5b1e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c0644ade7f549321e61eca3fe284692ad929ecca361fd150d7cd3f07cc5b1e9?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/akkuokok.de\\\/blog\"],\"url\":\"https:\\\/\\\/www.akkuokok.de\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Das Asus Zenbook S 13 OLED ist ein hervorragender Laptop - Akkus &amp; Ladeger\u00e4te Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.akkuokok.de\/blog\/2025\/04\/28\/das-asus-zenbook-s-13-oled-ist-ein-hervorragender-laptop\/","og_locale":"de_DE","og_type":"article","og_title":"Das Asus Zenbook S 13 OLED ist ein hervorragender Laptop - Akkus &amp; Ladeger\u00e4te Blog","og_description":"Mit seinem leichten Geh\u00e4use, dem wundersch\u00f6nen OLED-Display und der langen Akkulaufzeit wird das Zenbook S 13 OLED PC-Benutzer mit Sicherheit begeistern. Aus diesem Grund erh\u00e4lt das Asus Zenbook S 13 OLED nicht die Aufmerksamkeit, die es verdient. Dieser 13-Zoll-Laptop ist in vielerlei Hinsicht dem XPS, MacBook und Yoga ebenb\u00fcrtig, hat jedoch keinen bekannteren Namen. Es [&hellip;]","og_url":"https:\/\/www.akkuokok.de\/blog\/2025\/04\/28\/das-asus-zenbook-s-13-oled-ist-ein-hervorragender-laptop\/","og_site_name":"Akkus &amp; Ladeger\u00e4te Blog","article_published_time":"2025-04-28T09:31:15+00:00","article_modified_time":"2025-04-28T09:31:16+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.akkuokok.de\/blog\/2025\/04\/28\/das-asus-zenbook-s-13-oled-ist-ein-hervorragender-laptop\/#article","isPartOf":{"@id":"https:\/\/www.akkuokok.de\/blog\/2025\/04\/28\/das-asus-zenbook-s-13-oled-ist-ein-hervorragender-laptop\/"},"author":{"name":"admin","@id":"https:\/\/www.akkuokok.de\/blog\/#\/schema\/person\/0e78375375f076b526d126d5e46432b5"},"headline":"Das Asus Zenbook S 13 OLED ist ein hervorragender Laptop","datePublished":"2025-04-28T09:31:15+00:00","dateModified":"2025-04-28T09:31:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.akkuokok.de\/blog\/2025\/04\/28\/das-asus-zenbook-s-13-oled-ist-ein-hervorragender-laptop\/"},"wordCount":415,"commentCount":0,"articleSection":["Laptop Akku"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.akkuokok.de\/blog\/2025\/04\/28\/das-asus-zenbook-s-13-oled-ist-ein-hervorragender-laptop\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.akkuokok.de\/blog\/2025\/04\/28\/das-asus-zenbook-s-13-oled-ist-ein-hervorragender-laptop\/","url":"https:\/\/www.akkuokok.de\/blog\/2025\/04\/28\/das-asus-zenbook-s-13-oled-ist-ein-hervorragender-laptop\/","name":"Das Asus Zenbook S 13 OLED ist ein hervorragender Laptop - Akkus &amp; Ladeger\u00e4te Blog","isPartOf":{"@id":"https:\/\/www.akkuokok.de\/blog\/#website"},"datePublished":"2025-04-28T09:31:15+00:00","dateModified":"2025-04-28T09:31:16+00:00","author":{"@id":"https:\/\/www.akkuokok.de\/blog\/#\/schema\/person\/0e78375375f076b526d126d5e46432b5"},"breadcrumb":{"@id":"https:\/\/www.akkuokok.de\/blog\/2025\/04\/28\/das-asus-zenbook-s-13-oled-ist-ein-hervorragender-laptop\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.akkuokok.de\/blog\/2025\/04\/28\/das-asus-zenbook-s-13-oled-ist-ein-hervorragender-laptop\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.akkuokok.de\/blog\/2025\/04\/28\/das-asus-zenbook-s-13-oled-ist-ein-hervorragender-laptop\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.akkuokok.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Das Asus Zenbook S 13 OLED ist ein hervorragender Laptop"}]},{"@type":"WebSite","@id":"https:\/\/www.akkuokok.de\/blog\/#website","url":"https:\/\/www.akkuokok.de\/blog\/","name":"Akkus &amp; Ladeger\u00e4te Blog","description":"Akkus &amp; Ladeger\u00e4te f\u00fcr Smartphone, Tablet, Werkzeug &amp; Notebook!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.akkuokok.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.akkuokok.de\/blog\/#\/schema\/person\/0e78375375f076b526d126d5e46432b5","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/7c0644ade7f549321e61eca3fe284692ad929ecca361fd150d7cd3f07cc5b1e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7c0644ade7f549321e61eca3fe284692ad929ecca361fd150d7cd3f07cc5b1e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7c0644ade7f549321e61eca3fe284692ad929ecca361fd150d7cd3f07cc5b1e9?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/akkuokok.de\/blog"],"url":"https:\/\/www.akkuokok.de\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.akkuokok.de\/blog\/wp-json\/wp\/v2\/posts\/1547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.akkuokok.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.akkuokok.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.akkuokok.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.akkuokok.de\/blog\/wp-json\/wp\/v2\/comments?post=1547"}],"version-history":[{"count":1,"href":"https:\/\/www.akkuokok.de\/blog\/wp-json\/wp\/v2\/posts\/1547\/revisions"}],"predecessor-version":[{"id":1548,"href":"https:\/\/www.akkuokok.de\/blog\/wp-json\/wp\/v2\/posts\/1547\/revisions\/1548"}],"wp:attachment":[{"href":"https:\/\/www.akkuokok.de\/blog\/wp-json\/wp\/v2\/media?parent=1547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.akkuokok.de\/blog\/wp-json\/wp\/v2\/categories?post=1547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.akkuokok.de\/blog\/wp-json\/wp\/v2\/tags?post=1547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}